{"id":4281,"date":"2026-04-30T14:16:31","date_gmt":"2026-04-30T14:16:31","guid":{"rendered":"https:\/\/villapaladina.com\/?page_id=4281"},"modified":"2026-04-30T14:27:26","modified_gmt":"2026-04-30T14:27:26","slug":"spa","status":"publish","type":"page","link":"https:\/\/villapaladina.com\/fr\/spa\/","title":{"rendered":"SPA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"region.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4281","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SPA - Villa Paladina<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SPA - Villa Paladina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/villapaladina.com\/fr\/spa\/\" \/>\n<meta property=\"og:site_name\" content=\"Villa Paladina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/villapaladina\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-30T14:27:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/villapaladina.com\/fr\/spa\/\",\"url\":\"https:\/\/villapaladina.com\/fr\/spa\/\",\"name\":\"SPA - Villa Paladina\",\"isPartOf\":{\"@id\":\"https:\/\/villapaladina.com\/#website\"},\"datePublished\":\"2026-04-30T14:16:31+00:00\",\"dateModified\":\"2026-04-30T14:27:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/villapaladina.com\/fr\/spa\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/villapaladina.com\/fr\/spa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/villapaladina.com\/fr\/spa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/villapaladina.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SPA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/villapaladina.com\/#website\",\"url\":\"https:\/\/villapaladina.com\/\",\"name\":\"Villa Paladina\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/villapaladina.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/villapaladina.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/villapaladina.com\/#organization\",\"name\":\"Villa Paladina\",\"url\":\"https:\/\/villapaladina.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/villapaladina.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/villapaladina.com\/wp-content\/uploads\/2020\/01\/logo.png\",\"contentUrl\":\"https:\/\/villapaladina.com\/wp-content\/uploads\/2020\/01\/logo.png\",\"width\":200,\"height\":163,\"caption\":\"Villa Paladina\"},\"image\":{\"@id\":\"https:\/\/villapaladina.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/villapaladina\",\"https:\/\/www.instagram.com\/villapaladina\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SPA - Villa Paladina","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"SPA - Villa Paladina","og_url":"https:\/\/villapaladina.com\/fr\/spa\/","og_site_name":"Villa Paladina","article_publisher":"https:\/\/www.facebook.com\/villapaladina","article_modified_time":"2026-04-30T14:27:26+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/villapaladina.com\/fr\/spa\/","url":"https:\/\/villapaladina.com\/fr\/spa\/","name":"SPA - Villa Paladina","isPartOf":{"@id":"https:\/\/villapaladina.com\/#website"},"datePublished":"2026-04-30T14:16:31+00:00","dateModified":"2026-04-30T14:27:26+00:00","breadcrumb":{"@id":"https:\/\/villapaladina.com\/fr\/spa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/villapaladina.com\/fr\/spa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/villapaladina.com\/fr\/spa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/villapaladina.com\/fr\/"},{"@type":"ListItem","position":2,"name":"SPA"}]},{"@type":"WebSite","@id":"https:\/\/villapaladina.com\/#website","url":"https:\/\/villapaladina.com\/","name":"Villa Paladina","description":"","publisher":{"@id":"https:\/\/villapaladina.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/villapaladina.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/villapaladina.com\/#organization","name":"Villa Paladina","url":"https:\/\/villapaladina.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/villapaladina.com\/#\/schema\/logo\/image\/","url":"https:\/\/villapaladina.com\/wp-content\/uploads\/2020\/01\/logo.png","contentUrl":"https:\/\/villapaladina.com\/wp-content\/uploads\/2020\/01\/logo.png","width":200,"height":163,"caption":"Villa Paladina"},"image":{"@id":"https:\/\/villapaladina.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/villapaladina","https:\/\/www.instagram.com\/villapaladina\/"]}]}},"_links":{"self":[{"href":"https:\/\/villapaladina.com\/fr\/wp-json\/wp\/v2\/pages\/4281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/villapaladina.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/villapaladina.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/villapaladina.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/villapaladina.com\/fr\/wp-json\/wp\/v2\/comments?post=4281"}],"version-history":[{"count":0,"href":"https:\/\/villapaladina.com\/fr\/wp-json\/wp\/v2\/pages\/4281\/revisions"}],"wp:attachment":[{"href":"https:\/\/villapaladina.com\/fr\/wp-json\/wp\/v2\/media?parent=4281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}